{"id":93,"count":10,"description":"Die ESK wird 50 \u2013 da d\u00fcrfen Gl\u00fcckw\u00fcnsche nicht fehlen! Ob kurz oder lang, ernst oder lustig: Hinterlass Deinen Gru\u00df und feier mit uns.","link":"https:\/\/europaschulekoeln.eu\/blog\/category\/geburtstagsgruesse\/","name":"50+ Geburtstagsgr\u00fc\u00dfe","slug":"geburtstagsgruesse","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/europaschulekoeln.eu\/blog\/wp-json\/wp\/v2\/categories\/93","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/europaschulekoeln.eu\/blog\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/europaschulekoeln.eu\/blog\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/europaschulekoeln.eu\/blog\/wp-json\/wp\/v2\/posts?categories=93"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}